{"id":15115,"date":"2017-03-22T20:30:00","date_gmt":"2017-03-23T00:30:00","guid":{"rendered":"https:\/\/dev.sportspecialists.ca\/?p=336"},"modified":"2017-03-22T20:30:00","modified_gmt":"2017-03-23T00:30:00","slug":"4-etapes-pour-ameliorer-votre-golf","status":"publish","type":"post","link":"https:\/\/sportspecialists.ca\/fr\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/","title":{"rendered":"4 \u00e9tapes pour am\u00e9liorer votre golf!"},"content":{"rendered":"<p>4 &eacute;tapes pour faciliter l&rsquo;&eacute;lan du golf<\/p>\n<p>&nbsp;<\/p>\n<p>Voudriez-vous plus de FOUGUE dans votre &eacute;lan?<\/p>\n<p>&nbsp;<\/p>\n<p>Joe #1: &laquo;&nbsp;J&rsquo;ai vraiment bien frapp&eacute; la balle! 220 verges!&nbsp;&raquo;<\/p>\n<p>&nbsp;<\/p>\n<p>Joe #2: &laquo;&nbsp;As-tu vu mon coup? Il atteignait facilement 295 verges!&nbsp;&raquo;<\/p>\n<p>&nbsp;<\/p>\n<p>Joe #1: &laquo;&nbsp;S&eacute;rieusement! Qu&rsquo;est-ce qui te rend si puissant?&nbsp;&raquo;<\/p>\n<p>&nbsp;<\/p>\n<p>Joe #2: &laquo;&nbsp;Je pratique les 4 mesures essentielles que les professionnels des Sp&eacute;cialistes du S.P.O.R.T. m&rsquo;ont enseign&eacute;es!&nbsp;&raquo;<\/p>\n<p>&nbsp;<\/p>\n<p>C&rsquo;est vrai! 4 &eacute;tapes pour am&eacute;liorer l&rsquo;&eacute;lan au golf!<\/p>\n<p>&nbsp;<\/p>\n<p>La flexibilit&eacute;:<\/p>\n<p>Vous n&rsquo;avez pas besoin d&rsquo;&ecirc;tre Gumby (un personnage de F&eacute;lix le Chat) pour frapper la balle de golf, ni d&rsquo;&ecirc;tre un contorsionniste afin de frapper la balle de fa&ccedil;on efficace. Vous devrez vous assurer d&rsquo;avoir une flexibilit&eacute; ad&eacute;quate pour pratiquer votre sport. Trouvez vos points de tension et &eacute;tirez-les! Vous n&rsquo;avez PAS besoin de tout &eacute;tirer; simplement les muscles avec de la tension.<\/p>\n<p>&nbsp;<\/p>\n<p>Stabilit&eacute;:<\/p>\n<p>Cela ne veut PAS dire que vous allez jongler avec des quilles en feu en vous tenant sur une surface instable avec vos yeux ferm&eacute;s!&nbsp; La stabilit&eacute; des articulations indique que celles-ci sont con&ccedil;ues pour r&eacute;sister des forces de toutes les directions. Par exemple&nbsp;: Vos &eacute;paules doivent &ecirc;tre stables lorsque vous &ecirc;tes au haut de votre &eacute;lan arri&egrave;re et &agrave; la fin de votre &eacute;lan.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Force:<\/p>\n<p>La force peut seulement &ecirc;tre int&eacute;gr&eacute;e lorsque la flexibilit&eacute; et la stabilit&eacute; ont &eacute;t&eacute;s &eacute;tablies. Renforcissez uniquement les muscles qui sont faibles! Si vous pouvez squatter proprement, mais que vous avez de la difficult&eacute; &agrave; ex&eacute;cuter une fente correctement, pourquoi mettre plus de squats dans votre programme d&rsquo;exercices? Il faut travailler sur ces faiblesses!<\/p>\n<p>&nbsp;<\/p>\n<p>Puissance:<\/p>\n<p>L&agrave; on parle! Si vous avez ma&icirc;tris&eacute; les 3 stades pr&eacute;c&eacute;dents, vous FRAPPEREZ la balle plus loin&hellip;peut-&ecirc;tre pas 295 verges, mais plus loin que jamais! Et la MEILLEURE partie: vous r&eacute;duirez les risques de blessures!<\/p>\n<p>&nbsp;<\/p>\n<p>La moral de l&rsquo;histoire:<\/p>\n<p>Vous n&rsquo;ARRIVEREZ pas &agrave; vous en sortir &agrave; essayant simplement de surpasser vos amis. Le golf est un sport tr&egrave;s technique. Il requiert du &laquo;&nbsp;timing&nbsp;&raquo;, de la coordination main-&oelig;il, un transfert de poids, une excellente posture d&rsquo;adresse sans aucunes erreurs dans le positionnement tout au long de l&rsquo;&eacute;lan! Alors, il faut&nbsp;: s&rsquo;&eacute;tirer, se stabiliser, se renforcir et vous r&eacute;colterez les fruits de votre dur labeur avec les exercices de puissance!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>4 &eacute;tapes pour faciliter l&rsquo;&eacute;lan du golf &nbsp; Voudriez-vous plus de FOUGUE dans votre &eacute;lan? &nbsp; Joe #1: &laquo;&nbsp;J&rsquo;ai vraiment bien frapp&eacute; la balle! 220 verges!&nbsp;&raquo; &nbsp; Joe #2: &laquo;&nbsp;As-tu vu mon coup? Il atteignait facilement 295 verges!&nbsp;&raquo; &nbsp; Joe #1: &laquo;&nbsp;S&eacute;rieusement! Qu&rsquo;est-ce qui te rend si puissant?&nbsp;&raquo; &nbsp; Joe #2: &laquo;&nbsp;Je pratique les 4&#8230;<\/p>\n","protected":false},"author":2,"featured_media":13805,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-15115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-golf-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 \u00e9tapes pour am\u00e9liorer votre golf! - Sport Specialists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 \u00e9tapes pour am\u00e9liorer votre golf! - Sport Specialists\" \/>\n<meta property=\"og:description\" content=\"4 &eacute;tapes pour faciliter l&rsquo;&eacute;lan du golf &nbsp; Voudriez-vous plus de FOUGUE dans votre &eacute;lan? &nbsp; Joe #1: &laquo;&nbsp;J&rsquo;ai vraiment bien frapp&eacute; la balle! 220 verges!&nbsp;&raquo; &nbsp; Joe #2: &laquo;&nbsp;As-tu vu mon coup? Il atteignait facilement 295 verges!&nbsp;&raquo; &nbsp; Joe #1: &laquo;&nbsp;S&eacute;rieusement! Qu&rsquo;est-ce qui te rend si puissant?&nbsp;&raquo; &nbsp; Joe #2: &laquo;&nbsp;Je pratique les 4...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/\" \/>\n<meta property=\"og:site_name\" content=\"Sport Specialists\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-23T00:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sportspecialists.ca\/wp-content\/uploads\/2018\/09\/IMG_2970_Golf_v2_whiteFR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"940\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Peter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Peter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/\"},\"author\":{\"name\":\"Peter\",\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/#\\\/schema\\\/person\\\/9b802b851b6799acdfb254ab6206e7a1\"},\"headline\":\"4 \u00e9tapes pour am\u00e9liorer votre golf!\",\"datePublished\":\"2017-03-23T00:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/\"},\"wordCount\":511,\"image\":{\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sportspecialists.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/IMG_2970_Golf_v2_whiteFR.jpg\",\"articleSection\":[\"Golf\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/\",\"url\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/\",\"name\":\"4 \u00e9tapes pour am\u00e9liorer votre golf! - Sport Specialists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sportspecialists.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/IMG_2970_Golf_v2_whiteFR.jpg\",\"datePublished\":\"2017-03-23T00:30:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/#\\\/schema\\\/person\\\/9b802b851b6799acdfb254ab6206e7a1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sportspecialists.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/IMG_2970_Golf_v2_whiteFR.jpg\",\"contentUrl\":\"https:\\\/\\\/sportspecialists.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/IMG_2970_Golf_v2_whiteFR.jpg\",\"width\":940,\"height\":940},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/2017\\\/03\\\/22\\\/4-etapes-pour-ameliorer-votre-golf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sportspecialists.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 \u00e9tapes pour am\u00e9liorer votre golf!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/#website\",\"url\":\"https:\\\/\\\/sportspecialists.ca\\\/\",\"name\":\"Sport Specialists\",\"description\":\"We&#039;re open for therapy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sportspecialists.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sportspecialists.ca\\\/#\\\/schema\\\/person\\\/9b802b851b6799acdfb254ab6206e7a1\",\"name\":\"Peter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65d99650b039bc3e8d418fa990fcab35f3e2fe929790bc6c4f6fcd711abfce11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65d99650b039bc3e8d418fa990fcab35f3e2fe929790bc6c4f6fcd711abfce11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65d99650b039bc3e8d418fa990fcab35f3e2fe929790bc6c4f6fcd711abfce11?s=96&d=mm&r=g\",\"caption\":\"Peter\"},\"url\":\"https:\\\/\\\/sportspecialists.ca\\\/fr\\\/author\\\/peter\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 \u00e9tapes pour am\u00e9liorer votre golf! - Sport Specialists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/","og_locale":"fr_FR","og_type":"article","og_title":"4 \u00e9tapes pour am\u00e9liorer votre golf! - Sport Specialists","og_description":"4 &eacute;tapes pour faciliter l&rsquo;&eacute;lan du golf &nbsp; Voudriez-vous plus de FOUGUE dans votre &eacute;lan? &nbsp; Joe #1: &laquo;&nbsp;J&rsquo;ai vraiment bien frapp&eacute; la balle! 220 verges!&nbsp;&raquo; &nbsp; Joe #2: &laquo;&nbsp;As-tu vu mon coup? Il atteignait facilement 295 verges!&nbsp;&raquo; &nbsp; Joe #1: &laquo;&nbsp;S&eacute;rieusement! Qu&rsquo;est-ce qui te rend si puissant?&nbsp;&raquo; &nbsp; Joe #2: &laquo;&nbsp;Je pratique les 4...","og_url":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/","og_site_name":"Sport Specialists","article_published_time":"2017-03-23T00:30:00+00:00","og_image":[{"width":940,"height":940,"url":"https:\/\/sportspecialists.ca\/wp-content\/uploads\/2018\/09\/IMG_2970_Golf_v2_whiteFR.jpg","type":"image\/jpeg"}],"author":"Peter","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Peter","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/#article","isPartOf":{"@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/"},"author":{"name":"Peter","@id":"https:\/\/sportspecialists.ca\/#\/schema\/person\/9b802b851b6799acdfb254ab6206e7a1"},"headline":"4 \u00e9tapes pour am\u00e9liorer votre golf!","datePublished":"2017-03-23T00:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/"},"wordCount":511,"image":{"@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/#primaryimage"},"thumbnailUrl":"https:\/\/sportspecialists.ca\/wp-content\/uploads\/2018\/09\/IMG_2970_Golf_v2_whiteFR.jpg","articleSection":["Golf"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/","url":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/","name":"4 \u00e9tapes pour am\u00e9liorer votre golf! - Sport Specialists","isPartOf":{"@id":"https:\/\/sportspecialists.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/#primaryimage"},"image":{"@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/#primaryimage"},"thumbnailUrl":"https:\/\/sportspecialists.ca\/wp-content\/uploads\/2018\/09\/IMG_2970_Golf_v2_whiteFR.jpg","datePublished":"2017-03-23T00:30:00+00:00","author":{"@id":"https:\/\/sportspecialists.ca\/#\/schema\/person\/9b802b851b6799acdfb254ab6206e7a1"},"breadcrumb":{"@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/#primaryimage","url":"https:\/\/sportspecialists.ca\/wp-content\/uploads\/2018\/09\/IMG_2970_Golf_v2_whiteFR.jpg","contentUrl":"https:\/\/sportspecialists.ca\/wp-content\/uploads\/2018\/09\/IMG_2970_Golf_v2_whiteFR.jpg","width":940,"height":940},{"@type":"BreadcrumbList","@id":"https:\/\/sportspecialists.ca\/2017\/03\/22\/4-etapes-pour-ameliorer-votre-golf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sportspecialists.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"4 \u00e9tapes pour am\u00e9liorer votre golf!"}]},{"@type":"WebSite","@id":"https:\/\/sportspecialists.ca\/#website","url":"https:\/\/sportspecialists.ca\/","name":"Sport Specialists","description":"We&#039;re open for therapy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sportspecialists.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sportspecialists.ca\/#\/schema\/person\/9b802b851b6799acdfb254ab6206e7a1","name":"Peter","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/65d99650b039bc3e8d418fa990fcab35f3e2fe929790bc6c4f6fcd711abfce11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/65d99650b039bc3e8d418fa990fcab35f3e2fe929790bc6c4f6fcd711abfce11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/65d99650b039bc3e8d418fa990fcab35f3e2fe929790bc6c4f6fcd711abfce11?s=96&d=mm&r=g","caption":"Peter"},"url":"https:\/\/sportspecialists.ca\/fr\/author\/peter\/"}]}},"_links":{"self":[{"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/posts\/15115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/comments?post=15115"}],"version-history":[{"count":0,"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/posts\/15115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/media\/13805"}],"wp:attachment":[{"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/media?parent=15115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/categories?post=15115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sportspecialists.ca\/fr\/wp-json\/wp\/v2\/tags?post=15115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}